{"id":3574,"date":"2017-12-21T18:26:40","date_gmt":"2017-12-21T18:26:40","guid":{"rendered":"https:\/\/idoloasis.pt\/?p=3574\/"},"modified":"2017-12-21T18:26:40","modified_gmt":"2017-12-21T18:26:40","slug":"treinador-idoloasis-armando-evangelista-conquista-grande-vitoria-frente-ao-academico-de-viseu-na-ledman-ligapro","status":"publish","type":"post","link":"https:\/\/idoloasis.pt\/en\/treinador-idoloasis-armando-evangelista-conquista-grande-vitoria-frente-ao-academico-de-viseu-na-ledman-ligapro\/","title":{"rendered":"Treinador Idolo\u00e1sis Armando Evangelista conquista grande vit\u00f3ria frente ao Acad\u00e9mico de Viseu na Ledman LigaPro"},"content":{"rendered":"<p>O FC Penafiel, orientado por Armando Evangelista, foi hoje a casa do Acad\u00e9mico de Viseu (que liderava a tabela classificativa) vencer por 1-4.<\/p>\n<p>Com este resultado, a equipa de Penafiel fica com os mesmos pontos do 3\u00ba classificado, lugar que neste momento d\u00e1 acesso \u00e0 subida de divis\u00e3o e mantendo assim um registo impressionante na Ledman LigaPro desde que a nova equipa t\u00e9cnica chegou ao clube.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O FC Penafiel, orientado por Armando Evangelista, foi hoje a casa do Acad\u00e9mico de Viseu (que liderava a tabela classificativa) vencer por 1-4. Com este resultado, a equipa de Penafiel fica com os mesmos pontos do 3\u00ba classificado, lugar que neste momento d\u00e1 acesso \u00e0 subida de divis\u00e3o e mantendo assim um registo impressionante na [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3575,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-3574","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/idoloasis.pt\/en\/wp-json\/wp\/v2\/posts\/3574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/idoloasis.pt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/idoloasis.pt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/idoloasis.pt\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/idoloasis.pt\/en\/wp-json\/wp\/v2\/comments?post=3574"}],"version-history":[{"count":0,"href":"https:\/\/idoloasis.pt\/en\/wp-json\/wp\/v2\/posts\/3574\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/idoloasis.pt\/en\/wp-json\/wp\/v2\/media\/3575"}],"wp:attachment":[{"href":"https:\/\/idoloasis.pt\/en\/wp-json\/wp\/v2\/media?parent=3574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/idoloasis.pt\/en\/wp-json\/wp\/v2\/categories?post=3574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/idoloasis.pt\/en\/wp-json\/wp\/v2\/tags?post=3574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}